{"id":40596,"date":"2017-12-14T03:19:08","date_gmt":"2017-12-14T08:19:08","guid":{"rendered":"\/non-classifiee\/brexit-talks-sufficient-progress-critical-european-trade-stakeholders\/"},"modified":"2018-01-27T03:22:05","modified_gmt":"2018-01-27T08:22:05","slug":"voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen","status":"publish","type":"post","link":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/","title":{"rendered":"Voici les raisons pour lesquelles les \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb r\u00e9alis\u00e9s durant les n\u00e9gociations sur le Brexit sont si importants pour les acteurs du commerce europ\u00e9en"},"content":{"rendered":"<h3>Cet article a \u00e9t\u00e9 publi\u00e9 dans le\u00a0<a href=\"http:\/\/www.globaltrademag.com\/eu-trade\/brexit-talks-sufficient-progress-critical-european-trade-stakeholders\">Global Trade Magazine<\/a>\u00a0le 14 d\u00e9cembre 2017<\/h3>\n<div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-39905 size-medium\" src=\"\/livingston-content\/uploads\/2017\/12\/iStock-585605642-2-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" \/><\/p>\n<\/div>\n<p><em>Par Philip\u00a0Sutter, directeur de l\u2019analyse strat\u00e9gique au sein de la division de Gestion du commerce mondial de l\u2019entreprise de services commerciaux, la\u00a0<\/em><a href=\"\/\"><em>Soci\u00e9t\u00e9 internationale Livingston inc<\/em><\/a><em>.<\/em><\/p>\n<p>Dans la foul\u00e9e des nouvelles n\u00e9gatives pr\u00e9disant une impasse des n\u00e9gociations sur le Brexit, la Commission europ\u00e9enne a fait une annonce importante la semaine derni\u00e8re. La Commission avise maintenant le Conseil europ\u00e9en que des \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb ont \u00e9t\u00e9 r\u00e9alis\u00e9s au cours de la premi\u00e8re \u00e9tape des n\u00e9gociations portant sur les conditions de la sortie du Royaume-Uni de l\u2019Union europ\u00e9enne. Finalement, il existe une lueur de certitude laissant croire que les deux parties atteindront un accord global en temps opportun; un accord tr\u00e8s important pour int\u00e9r\u00eats des parties concern\u00e9es, mais surtout pour les commer\u00e7ants et les multinationales europ\u00e9ens.<\/p>\n<p>La lueur d\u2019espoir a \u00e9t\u00e9 sans doute bien accueillie par les entreprises am\u00e9ricaines qui ont investi consid\u00e9rablement dans le commerce entre les \u00c9tats-Unis et le Royaume-Uni. En effet, selon un <a href=\"https:\/\/www.uschamber.com\/sites\/default\/files\/u.s._chamber_testimony_chorlins_120617.pdf\">r\u00e9cent t\u00e9moignage<\/a> de la Chambre de commerce am\u00e9ricaine devant le sous-comit\u00e9 du Comit\u00e9 des affaires \u00e9trang\u00e8res de la Chambre des repr\u00e9sentants sur l\u2019Europe, l\u2019Eurasie et les menaces \u00e9mergentes, le commerce bilat\u00e9ral entre les \u00c9tats-Unis et le Royaume-Uni s\u2019\u00e9l\u00e8ve \u00e0 plus de 235\u00a0milliards de dollars et 2,5\u00a0millions d\u2019emplois aux \u00c9tats-Unis d\u00e9pendent des \u00e9changes entre ces deux pays. Ce t\u00e9moignage qualifie l\u2019impasse des n\u00e9gociations sur le Brexit de \u00ab\u00a0d\u00e9sastre pour les entreprises am\u00e9ricaines\u00a0\u00bb tout en soulignant qu\u2019elle pourrait avoir des cons\u00e9quences n\u00e9gatives sur les consommateurs britanniques sur le plan de la de croissance des prix.<\/p>\n<p>En vertu des dispositions de l\u2019article\u00a050 du trait\u00e9 de l\u2019Union europ\u00e9enne, il est recommand\u00e9 aux parties de r\u00e9aliser des progr\u00e8s suffisants avant d\u2019entamer d\u2019autres n\u00e9gociations concernant un accord futur entre l\u2019UE et le R.-U. Le Conseil europ\u00e9en proc\u00e9dera au vote officiel le 15\u00a0d\u00e9cembre, mais on s\u2019attend \u00e0 ce qu\u2019il suive la recommandation de la Commission.<\/p>\n<p>Les n\u00e9gociateurs du Royaume-Uni et de l\u2019Union europ\u00e9enne sur le Brexit ont publi\u00e9 un <a href=\"https:\/\/g8fip1kplyr33r3krz5b97d1-wpengine.netdna-ssl.com\/wp-content\/uploads\/2017\/12\/joint_report.pdf\">rapport conjoint<\/a>. Voici un aper\u00e7u de certains points cl\u00e9s du rapport\u00a0:<\/p>\n<ul>\n<li>Un accord sur la m\u00e9thodologie du r\u00e8glement financier qui entra\u00eenerait une facture de l\u2019ordre de\u00a040 \u00e0 45\u00a0milliards d\u2019euros (sous r\u00e9serve d\u2019un accord global), y compris toutes les obligations financi\u00e8res pr\u00e9c\u00e9dentes et la contribution du Royaume-Uni au budget europ\u00e9en jusqu\u2019\u00e0 la fin de\u00a02020.<\/li>\n<li>Donner \u00e0 la Cour europ\u00e9enne de justice (CEJ) le pouvoir de temporiser apr\u00e8s les huit ann\u00e9es qui suivent le jour du Brexit pour permettre d\u2019avoir une certitude concernant les pr\u00e9occupations des entreprises.<\/li>\n<li>Donner une protection r\u00e9ciproque aux citoyens de l\u2019Union europ\u00e9enne et du Royaume-Uni pour garantir l&rsquo;exercice effectif des droits d\u00e9coulant des lois de l\u2019Union, tout en tenant compte des circonstances individuelles.<\/li>\n<li>Veiller \u00e0 ce que la fronti\u00e8re avec l\u2019Irlande ne soit pas assujettie \u00e0 des contr\u00f4les frontaliers; permettre le libre acc\u00e8s aux entreprises de l\u2019Irlande du Nord et respecter l\u2019accord du Vendredi saint de\u00a01998.<\/li>\n<\/ul>\n<p>En ce qui concerne l\u2019accord futur, le Royaume-Uni pourrait opter pour un accord hybride qui est plus solide que l\u2019Accord \u00e9conomique et commercial global (AECG) avec le Canada, mais sans comporter autant de restrictions que celles impos\u00e9es \u00e0 la Norv\u00e8ge actuellement dans le cadre de l\u2019Association europ\u00e9enne de libre-\u00e9change (AELE). L\u2019objectif consisterait \u00e0 terminer les n\u00e9gociations avant le quatri\u00e8me trimestre de\u00a02018 pour laisser le temps au Parlement europ\u00e9en de donner son consentement et au Royaume-Uni d\u2019exprimer son approbation avant le 29\u00a0mars\u00a02019.<\/p>\n<p>Il reste encore beaucoup \u00e0 faire, mais peu de temps avant le Brexit. Cependant, les deux parties esp\u00e8rent que la d\u00e9claration des progr\u00e8s suffisants r\u00e9duira le ton souvent acrimonieux et les gesticulations constantes ayant marqu\u00e9 les n\u00e9gociations jusqu\u2019\u00e0 pr\u00e9sent et qu\u2019elles pencheront en faveur d\u2019une prise de d\u00e9cision claire et coh\u00e9rente. Les commer\u00e7ants internationaux ont besoin de d\u00e9tails \u2013 qui sont actuellement tr\u00e8s insuffisants \u2013 pour appuyer leurs plans strat\u00e9giques sur des sujets comme l\u2019exposition aux droits et \u00e0 l\u2019imp\u00f4t, les proc\u00e9dures de courtage et de d\u00e9douanement, les mises \u00e0 jour des syst\u00e8mes, les changements r\u00e8glementaires et l\u2019administration de l\u2019accord de libre-\u00e9change.<\/p>\n<p>Les deux parties ont int\u00e9r\u00eat \u00e0 prendre la bonne d\u00e9cision et \u00e0 pr\u00e9server la circulation continue des marchandises entre le Royaume-Uni et l\u2019Union europ\u00e9enne. Elles sont conscientes des risques d\u2019une position \u00ab\u00a0au bord du gouffre\u00a0\u00bb. En outre, la prise d\u2019une d\u00e9cision \u00e9clair\u00e9e rev\u00eat une importance au-del\u00e0 de l&rsquo;Europe. De nombreuses multinationales, comme celles aux \u00c9tats-Unis, se servent du Royaume-Uni comme point d\u2019entr\u00e9e ou de sortie pour le commerce europ\u00e9en. Elles craignent l\u2019instauration potentielle de r\u00e9gimes r\u00e9glementaires disparates entre les deux parties et le risque de changements r\u00e9glementaires au Royaume-Uni pour des secteurs cl\u00e9s comme l\u2019industrie pharmaceutique et l\u2019aviation.<\/p>\n<p>Il y aura probablement au moins une p\u00e9riode de mise en \u0153uvre de deux\u00a0ans. Celle-ci permettra aux gouvernements et aux entreprises d\u2019avoir plus de temps pour prendre les dispositions requises. Des prolongations suppl\u00e9mentaires peuvent \u00eatre possibles dans certains secteurs industriels.<\/p>\n<p>\u00c0 un niveau \u00e9lev\u00e9, un accord futur doit toujours \u00eatre ax\u00e9 sur les quatre libert\u00e9s de l\u2019UE\u00a0: libert\u00e9 de circulation des marchandises, des personnes, des services et des capitaux \u00e0 travers les fronti\u00e8res. Les deux\u00a0parties sont probablement en accord sur trois libert\u00e9s. Or, c\u2019est la circulation des personnes qui constitue le point de friction des n\u00e9gociations suivantes et c\u2019est aussi l\u2019axe essentiel sur lequel s\u2019articule le Brexit depuis le d\u00e9but. La question qui se pose maintenant\u00a0: dans quelle mesure les deux parties sont-elles dispos\u00e9es \u00e0 faire des concessions?<\/p>\n<p>Il est fort probable que les relations tournent mal; toutefois, la d\u00e9claration des \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb est un atout qu\u2019on ne devrait pas sous-estimer, mais plut\u00f4t reconna\u00eetre et privil\u00e9gier. Les n\u00e9gociateurs ont travaill\u00e9 dur pour atteindre ce r\u00e9sultat; aussi, dans l\u2019int\u00e9r\u00eat du commerce entre l\u2019Europe et ses partenaires, il est important que ces efforts se poursuivent.<\/p>\n<p><em>Philip\u00a0Sutter est le directeur de l\u2019analyse strat\u00e9gique de la division de gestion du commerce mondial de l\u2019entreprise de services commerciaux, la <\/em><a href=\"\/\"><em>Soci\u00e9t\u00e9 internationale Livingston.<\/em><\/a><\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cet article a \u00e9t\u00e9 publi\u00e9 dans le\u00a0Global Trade Magazine\u00a0le 14 d\u00e9cembre 2017 Par Philip\u00a0Sutter, directeur de l\u2019analyse strat\u00e9gique au sein de la division de Gestion du commerce mondial de l\u2019entreprise de services commerciaux, la\u00a0Soci\u00e9t\u00e9 internationale Livingston inc. Dans la foul\u00e9e des nouvelles n\u00e9gatives pr\u00e9disant une impasse des n\u00e9gociations sur le Brexit, la Commission europ\u00e9enne a<a class=\"excerpt-read-more\" href=\"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/\" title=\"ReadVoici les raisons pour lesquelles les \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb r\u00e9alis\u00e9s durant les n\u00e9gociations sur le Brexit sont si importants pour les acteurs du commerce europ\u00e9en\">&#8230; Read more &raquo;<\/a><\/p>\n","protected":false},"author":36,"featured_media":40594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[182],"class_list":["post-40596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nos-experts-vous-parlent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voici les raisons pour lesquelles les \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb r\u00e9alis\u00e9s durant les n\u00e9gociations sur le Brexit sont si importants pour les acteurs du commerce europ\u00e9en - Livingston International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voici les raisons pour lesquelles les \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb r\u00e9alis\u00e9s durant les n\u00e9gociations sur le Brexit sont si importants pour les acteurs du commerce europ\u00e9en - Livingston International\" \/>\n<meta property=\"og:description\" content=\"Cet article a \u00e9t\u00e9 publi\u00e9 dans le\u00a0Global Trade Magazine\u00a0le 14 d\u00e9cembre 2017 Par Philip\u00a0Sutter, directeur de l\u2019analyse strat\u00e9gique au sein de la division de Gestion du commerce mondial de l\u2019entreprise de services commerciaux, la\u00a0Soci\u00e9t\u00e9 internationale Livingston inc. Dans la foul\u00e9e des nouvelles n\u00e9gatives pr\u00e9disant une impasse des n\u00e9gociations sur le Brexit, la Commission europ\u00e9enne a... Read more &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/\" \/>\n<meta property=\"og:site_name\" content=\"Livingston International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/livingstoninternational\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-14T08:19:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-27T08:22:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.livingstonintl.com\/livingston-content\/uploads\/2018\/01\/25225921\/iStock-585605642-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2124\" \/>\n\t<meta property=\"og:image:height\" content=\"1411\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dan Ovsey\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dan Ovsey\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\\\/\"},\"author\":{\"name\":\"Dan Ovsey\",\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/#\\\/schema\\\/person\\\/41a41f5d824482db93829b4697ca9f37\"},\"headline\":\"Voici les raisons pour lesquelles les \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb r\u00e9alis\u00e9s durant les n\u00e9gociations sur le Brexit sont si importants pour les acteurs du commerce europ\u00e9en\",\"datePublished\":\"2017-12-14T08:19:08+00:00\",\"dateModified\":\"2018-01-27T08:22:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\\\/\"},\"wordCount\":1160,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.livingstonintl.com\\\/livingston-content\\\/uploads\\\/2018\\\/01\\\/25225921\\\/iStock-585605642-2.jpg\",\"articleSection\":[\"Nos experts vous parlent\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\\\/\",\"url\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\\\/\",\"name\":\"Voici les raisons pour lesquelles les \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb r\u00e9alis\u00e9s durant les n\u00e9gociations sur le Brexit sont si importants pour les acteurs du commerce europ\u00e9en - Livingston International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.livingstonintl.com\\\/livingston-content\\\/uploads\\\/2018\\\/01\\\/25225921\\\/iStock-585605642-2.jpg\",\"datePublished\":\"2017-12-14T08:19:08+00:00\",\"dateModified\":\"2018-01-27T08:22:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.livingstonintl.com\\\/livingston-content\\\/uploads\\\/2018\\\/01\\\/25225921\\\/iStock-585605642-2.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.livingstonintl.com\\\/livingston-content\\\/uploads\\\/2018\\\/01\\\/25225921\\\/iStock-585605642-2.jpg\",\"width\":2124,\"height\":1411,\"caption\":\"Negotiation of Great Britain and European Union (Brexit). Statesman or politicians with clasped hands.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voici les raisons pour lesquelles les \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb r\u00e9alis\u00e9s durant les n\u00e9gociations sur le Brexit sont si importants pour les acteurs du commerce europ\u00e9en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/\",\"name\":\"Livingston International\",\"description\":\"Simplify Trade\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/#organization\",\"name\":\"Livingston International\",\"url\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn.livingstonintl.com\\\/livingston-content\\\/uploads\\\/2022\\\/09\\\/12163235\\\/2022-livingston-fb.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.livingstonintl.com\\\/livingston-content\\\/uploads\\\/2022\\\/09\\\/12163235\\\/2022-livingston-fb.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Livingston International\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/livingstoninternational\",\"https:\\\/\\\/x.com\\\/livingston_intl\",\"https:\\\/\\\/linkedin.com\\\/company\\\/livingston-international\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livingstonintl.com\\\/fr\\\/#\\\/schema\\\/person\\\/41a41f5d824482db93829b4697ca9f37\",\"name\":\"Dan Ovsey\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d812bb5d2ce09a8dbfe560c16be7b5260f689323f5b82727809faa3e53644ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d812bb5d2ce09a8dbfe560c16be7b5260f689323f5b82727809faa3e53644ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d812bb5d2ce09a8dbfe560c16be7b5260f689323f5b82727809faa3e53644ed?s=96&d=mm&r=g\",\"caption\":\"Dan Ovsey\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voici les raisons pour lesquelles les \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb r\u00e9alis\u00e9s durant les n\u00e9gociations sur le Brexit sont si importants pour les acteurs du commerce europ\u00e9en - Livingston International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/","og_locale":"fr_FR","og_type":"article","og_title":"Voici les raisons pour lesquelles les \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb r\u00e9alis\u00e9s durant les n\u00e9gociations sur le Brexit sont si importants pour les acteurs du commerce europ\u00e9en - Livingston International","og_description":"Cet article a \u00e9t\u00e9 publi\u00e9 dans le\u00a0Global Trade Magazine\u00a0le 14 d\u00e9cembre 2017 Par Philip\u00a0Sutter, directeur de l\u2019analyse strat\u00e9gique au sein de la division de Gestion du commerce mondial de l\u2019entreprise de services commerciaux, la\u00a0Soci\u00e9t\u00e9 internationale Livingston inc. Dans la foul\u00e9e des nouvelles n\u00e9gatives pr\u00e9disant une impasse des n\u00e9gociations sur le Brexit, la Commission europ\u00e9enne a... Read more &raquo;","og_url":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/","og_site_name":"Livingston International","article_publisher":"https:\/\/www.facebook.com\/livingstoninternational","article_published_time":"2017-12-14T08:19:08+00:00","article_modified_time":"2018-01-27T08:22:05+00:00","og_image":[{"width":2124,"height":1411,"url":"https:\/\/cdn.livingstonintl.com\/livingston-content\/uploads\/2018\/01\/25225921\/iStock-585605642-2.jpg","type":"image\/jpeg"}],"author":"Dan Ovsey","twitter_misc":{"\u00c9crit par":"Dan Ovsey","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/#article","isPartOf":{"@id":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/"},"author":{"name":"Dan Ovsey","@id":"https:\/\/www.livingstonintl.com\/fr\/#\/schema\/person\/41a41f5d824482db93829b4697ca9f37"},"headline":"Voici les raisons pour lesquelles les \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb r\u00e9alis\u00e9s durant les n\u00e9gociations sur le Brexit sont si importants pour les acteurs du commerce europ\u00e9en","datePublished":"2017-12-14T08:19:08+00:00","dateModified":"2018-01-27T08:22:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/"},"wordCount":1160,"publisher":{"@id":"https:\/\/www.livingstonintl.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.livingstonintl.com\/livingston-content\/uploads\/2018\/01\/25225921\/iStock-585605642-2.jpg","articleSection":["Nos experts vous parlent"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/","url":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/","name":"Voici les raisons pour lesquelles les \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb r\u00e9alis\u00e9s durant les n\u00e9gociations sur le Brexit sont si importants pour les acteurs du commerce europ\u00e9en - Livingston International","isPartOf":{"@id":"https:\/\/www.livingstonintl.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/#primaryimage"},"image":{"@id":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.livingstonintl.com\/livingston-content\/uploads\/2018\/01\/25225921\/iStock-585605642-2.jpg","datePublished":"2017-12-14T08:19:08+00:00","dateModified":"2018-01-27T08:22:05+00:00","breadcrumb":{"@id":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/#primaryimage","url":"https:\/\/cdn.livingstonintl.com\/livingston-content\/uploads\/2018\/01\/25225921\/iStock-585605642-2.jpg","contentUrl":"https:\/\/cdn.livingstonintl.com\/livingston-content\/uploads\/2018\/01\/25225921\/iStock-585605642-2.jpg","width":2124,"height":1411,"caption":"Negotiation of Great Britain and European Union (Brexit). Statesman or politicians with clasped hands."},{"@type":"BreadcrumbList","@id":"https:\/\/www.livingstonintl.com\/fr\/voici-les-raisons-pour-lesquelles-les-progres-suffisants-realises-durant-les-negociations-sur-le-brexit-sont-si-importants-pour-les-acteurs-du-commerce-europeen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.livingstonintl.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Voici les raisons pour lesquelles les \u00ab\u00a0progr\u00e8s suffisants\u00a0\u00bb r\u00e9alis\u00e9s durant les n\u00e9gociations sur le Brexit sont si importants pour les acteurs du commerce europ\u00e9en"}]},{"@type":"WebSite","@id":"https:\/\/www.livingstonintl.com\/fr\/#website","url":"https:\/\/www.livingstonintl.com\/fr\/","name":"Livingston International","description":"Simplify Trade","publisher":{"@id":"https:\/\/www.livingstonintl.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livingstonintl.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.livingstonintl.com\/fr\/#organization","name":"Livingston International","url":"https:\/\/www.livingstonintl.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.livingstonintl.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.livingstonintl.com\/livingston-content\/uploads\/2022\/09\/12163235\/2022-livingston-fb.jpg","contentUrl":"https:\/\/cdn.livingstonintl.com\/livingston-content\/uploads\/2022\/09\/12163235\/2022-livingston-fb.jpg","width":1200,"height":630,"caption":"Livingston International"},"image":{"@id":"https:\/\/www.livingstonintl.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/livingstoninternational","https:\/\/x.com\/livingston_intl","https:\/\/linkedin.com\/company\/livingston-international"]},{"@type":"Person","@id":"https:\/\/www.livingstonintl.com\/fr\/#\/schema\/person\/41a41f5d824482db93829b4697ca9f37","name":"Dan Ovsey","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d812bb5d2ce09a8dbfe560c16be7b5260f689323f5b82727809faa3e53644ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d812bb5d2ce09a8dbfe560c16be7b5260f689323f5b82727809faa3e53644ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d812bb5d2ce09a8dbfe560c16be7b5260f689323f5b82727809faa3e53644ed?s=96&d=mm&r=g","caption":"Dan Ovsey"}}]}},"_links":{"self":[{"href":"https:\/\/wp.livingstonintl.com\/fr\/wp-json\/wp\/v2\/posts\/40596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.livingstonintl.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.livingstonintl.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.livingstonintl.com\/fr\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.livingstonintl.com\/fr\/wp-json\/wp\/v2\/comments?post=40596"}],"version-history":[{"count":0,"href":"https:\/\/wp.livingstonintl.com\/fr\/wp-json\/wp\/v2\/posts\/40596\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.livingstonintl.com\/fr\/wp-json\/wp\/v2\/media\/40594"}],"wp:attachment":[{"href":"https:\/\/wp.livingstonintl.com\/fr\/wp-json\/wp\/v2\/media?parent=40596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.livingstonintl.com\/fr\/wp-json\/wp\/v2\/categories?post=40596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}